{"id":12588,"date":"2022-11-22T15:55:46","date_gmt":"2022-11-22T20:55:46","guid":{"rendered":"https:\/\/www.une.edu.pe\/uneweb\/?p=12588"},"modified":"2022-11-23T12:04:46","modified_gmt":"2022-11-23T17:04:46","slug":"limpieza-de-playa-marquez-del-callao","status":"publish","type":"post","link":"https:\/\/www.une.edu.pe\/uneweb\/limpieza-de-playa-marquez-del-callao\/","title":{"rendered":"Limpieza de playa M\u00e1rquez del Callao"},"content":{"rendered":"\n<p><strong>Nota de Prensa N\u00b0 089-2022-OII-UNE<\/strong><\/p>\n\n\n\n<p>Contribuyendo\nal cuidado del medio ambiente, as\u00ed como buscando transmitir e integrar estas\nacciones en la sociedad se realiz\u00f3 la limpieza de la playa M\u00e1rquez del Callao a\ncargo del Voluntariado Universitario de la Facultad de Ciencias Empresariales.<\/p>\n\n\n\n<p>La actividad, que se realiz\u00f3 el viernes 18 de noviembre, estuvo organizada por la Coordinaci\u00f3n de Extensi\u00f3n Cultural y Proyecci\u00f3n Social de la FACE, dirigida por la Mg. Gloria Nizama Ruiz. Las acciones ejecutadas buscan favorecer el desarrollo de la formaci\u00f3n integral de los estudiantes y el fortalecimiento del perfil de los egresados, as\u00ed como el cumplimiento de los est\u00e1ndares 25 y 26 del proceso de acreditaci\u00f3n de la facultad.<\/p>\n\n\n\n<p>Los est\u00e1ndares en menci\u00f3n est\u00e1n referidos a la Responsabilidad Social Universitaria y Pol\u00edticas Ambientales respectivamente, vincul\u00e1ndose en esta actividad, en la generaci\u00f3n de actividades de impacto social con el compromiso ambiental en la promoci\u00f3n de la conservaci\u00f3n del medio ambiente.<\/p>\n\n\n\n<p>Docentes, estudiantes y personal administrativo de la FACE, que integran el voluntariado universitario, en coordinaci\u00f3n con la Municipalidad Provincial del Callao y la Marina de Guerra del Per\u00fa participaron activamente en la limpieza de una de las playas m\u00e1s contaminadas del pa\u00eds.<\/p>\n\n\n\n<p><strong>La Cantuta, 22 de noviembre de 2022.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092232-1024x578.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092232-1024x578.jpg\" alt=\"\" data-id=\"12590\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12590\" class=\"wp-image-12590\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092232-1024x578.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092232-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092232-768x433.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092138-1024x578.jpg\"><img decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092138-1024x578.jpg\" alt=\"\" data-id=\"12596\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12596\" class=\"wp-image-12596\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092138-1024x578.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092138-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092138-768x433.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092927-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092927-1024x576.jpg\" alt=\"\" data-id=\"12591\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12591\" class=\"wp-image-12591\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092927-1024x576.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092927-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_092927-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_093648-1024x576.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_093648-1024x576.jpg\" alt=\"\" data-id=\"12592\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12592\" class=\"wp-image-12592\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_093648-1024x576.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_093648-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_093648-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094005-1024x578.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094005-1024x578.jpg\" alt=\"\" data-id=\"12593\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12593\" class=\"wp-image-12593\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094005-1024x578.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094005-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094005-768x433.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094421-1024x576.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094421-1024x576.jpg\" alt=\"\" data-id=\"12594\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12594\" class=\"wp-image-12594\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094421-1024x576.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094421-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_094421-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_095753-1024x576.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_095753-1024x576.jpg\" alt=\"\" data-id=\"12595\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12595\" class=\"wp-image-12595\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_095753-1024x576.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_095753-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_095753-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_103504-1024x578.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_103504-1024x578.jpg\" alt=\"\" data-id=\"12597\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12597\" class=\"wp-image-12597\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_103504-1024x578.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_103504-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_103504-768x433.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_105627-1024x578.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_105627-1024x578.jpg\" alt=\"\" data-id=\"12598\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12598\" class=\"wp-image-12598\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_105627-1024x578.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_105627-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_105627-768x433.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_110445-1024x578.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_110445-1024x578.jpg\" alt=\"\" data-id=\"12599\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12599\" class=\"wp-image-12599\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_110445-1024x578.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_110445-300x169.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_110445-768x433.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_112940-1-1024x360.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"360\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_112940-1-1024x360.jpg\" alt=\"\" data-id=\"12601\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=12601\" class=\"wp-image-12601\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_112940-1-1024x360.jpg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_112940-1-300x105.jpg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/11\/20221118_112940-1-768x270.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul>\n ","protected":false},"excerpt":{"rendered":"<p>Nota de Prensa N\u00b0 089-2022-OII-UNE Contribuyendo al cuidado del medio ambiente, as\u00ed como buscando transmitir e integrar estas acciones en la sociedad se realiz\u00f3 la limpieza de la playa M\u00e1rquez del Callao a cargo del Voluntariado Universitario de la Facultad de Ciencias Empresariales. La actividad, que se realiz\u00f3 el viernes 18 de noviembre, estuvo organizada [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12589,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-12588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts\/12588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/comments?post=12588"}],"version-history":[{"count":7,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts\/12588\/revisions"}],"predecessor-version":[{"id":12629,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts\/12588\/revisions\/12629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/media\/12589"}],"wp:attachment":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/media?parent=12588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/categories?post=12588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/tags?post=12588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}