{"id":10639,"date":"2022-03-09T18:05:31","date_gmt":"2022-03-09T23:05:31","guid":{"rendered":"https:\/\/www.une.edu.pe\/uneweb\/?p=10639"},"modified":"2025-11-14T15:45:08","modified_gmt":"2025-11-14T20:45:08","slug":"realizan-sembrado-del-arbol-de-la-quina-en-la-une","status":"publish","type":"post","link":"https:\/\/www.une.edu.pe\/uneweb\/realizan-sembrado-del-arbol-de-la-quina-en-la-une\/","title":{"rendered":"Realizan sembrado del \u00e1rbol de la quina en la UNE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Nota de Prensa N\u00b0 019-2022-OII-UNE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el prop\u00f3sito de redescubrir, repoblar y concientizar sobre la\nimportancia medicinal, ambiental y forestal del \u00e1rbol de la quina, esta tarde se\nrealiz\u00f3 la siembra de esta planta en la sede central de la Universidad Nacional\nde Educaci\u00f3n Enrique Guzm\u00e1n y Valle, en el marco de las celebraciones por el\nBicentenario Institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos plantones de este \u00e1rbol, que simboliza al reino\nvegetal y a la riqueza natural en el Escudo Nacional del Per\u00fa, fueron donados y\nentregados por un grupo de siete egresados de la promoci\u00f3n 2017, G3, de la especialidad de Desarrollo\nAmbiental, r\u00e9gimen Semipresencial, de la Facultad de Agropecuaria y Nutrici\u00f3n\n(FAN) de la UNE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el acto participaron el\nDr. Rub\u00e9n Flores Rosas, decano de la FAN, el Dr.\nTiburcio Rufino Solano Le\u00f3n, quien lleg\u00f3 en representaci\u00f3n del vicerrector\nacad\u00e9mico, Dr. Vladimiro del Castillo Narro; as\u00ed como el Mg. Guillermo Atencia Guerra\ny la Mg. Victoria Vila Cano, docentes de Desarrollo Ambiental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Mg. Guillermo\nAtencia, dijo que esta actividad se realiza con la finalidad de contribuir al\nredescubrimiento y repoblamiento del \u00e1rbol de la quina, ya que hoy en d\u00eda se\nencuentra gravemente afectada, casi al punto de su desaparici\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, record\u00f3 que este \u00e1rbol cobr\u00f3 fama mundial por las propiedades\nfarmacol\u00f3gicas y medicinales presentes, sobre todo, en su corteza, que ayudaron\na salvar muchas vidas frente a enfermedades epid\u00e9micas, como la malaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, sostuvo\nque este proyecto de repoblamiento del \u00e1rbol de la quina significar\u00e1 un gran reto\npara los docentes y estudiantes de la FAN, ya que se debe producir un tipo de\nriego que simule su h\u00e1bitat natural, en la que debe alcanzar una altura de 10 a\n15 metros y m\u00e1s de un metro de di\u00e1metro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el\ndelegado de la promoci\u00f3n, Richard Noriega Mori Delegado, precis\u00f3 que hacen entrega\nde estos \u00e1rboles a la UNE para su respectivo estudio, investigaci\u00f3n y propagaci\u00f3n.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un reto en el\nque nos comprometimos como egresados para propagar el \u00e1rbol de la quina que est\u00e1\nen peligro de extinci\u00f3n y cuidar nuestra biodiversidad\u201d, afirmo el exalumno\ncantute\u00f1o, Richard Noriega. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Refiri\u00f3 adem\u00e1s que\nestas plantas provienen de aproximadamente 2,900 m s.n.m. a 10 km de la Fortaleza\nde Ku\u00e9lap (Amazonas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, detall\u00f3\nque las 2 plantas donadas tienen cerca de un a\u00f1o de vida, las cuales han pasado\npor un proceso de aclimataci\u00f3n de 8 meses en zonas cercanas al mar como el Callao,\nComas, San Juan de Lurigancho, y que una vez culminada su aclimataci\u00f3n la hicieron\nllegar a la UNE, en Chosica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, el decano, los docentes y estudiantes procedieron a realizar la siembra de una planta del \u00e1rbol de la quina en  la Facultad de Agropecuaria y Nutrici\u00f3n y la segunda planta en el frontis de la Biblioteca Central de la UNE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DATOS IMPORTANTES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Agricultura y Riego (Minagri), a trav\u00e9s de Agro Rural, est\u00e1 desarrollando un plan de repoblamiento del \u00e1rbol de la quina\u00a0en 10 departamentos del pa\u00eds. El objetivo es reforestar 145 hect\u00e1reas en el 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Propiedades medicinales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La corteza del \u00e1rbol de\nla quina posee diversos&nbsp;alcaloides\nnaturales, entre los que destaca la&nbsp;quinina, que tiene propiedades&nbsp;antipir\u00e9ticas (disminuye la fiebre), antipal\u00fadicas y analg\u00e9sicas,\npor lo que fue utilizada desde tiempos prehisp\u00e1nicos para tratar eficazmente\nenfermedades como la&nbsp;malaria&nbsp;o&nbsp;paludismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro alcaloide derivado de este \u00e1rbol es la&nbsp;quinidina, que se utiliza en el&nbsp;tratamiento de la frecuencia card\u00edaca anormal&nbsp;y\notros trastornos del ritmo card\u00edaco. Adem\u00e1s, la&nbsp;quinina&nbsp;posee principios&nbsp;astringentes, por su alta concentraci\u00f3n de taninos, por lo que\nayuda en la medicina tradicional para&nbsp;cicatrizar heridas y \u00falceras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Cantuta, 9 de marzo de 2022.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.03-PM-1024x576.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.03-PM-1024x576.jpeg\" alt=\"\" data-id=\"10641\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10641\" class=\"wp-image-10641\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.03-PM-1024x576.jpeg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.03-PM-300x169.jpeg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.03-PM-768x432.jpeg 768w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.03-PM.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.11-PM-1024x576.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.11-PM-1024x576.jpeg\" alt=\"\" data-id=\"10642\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10642\" class=\"wp-image-10642\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.11-PM-1024x576.jpeg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.11-PM-300x169.jpeg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.11-PM-768x432.jpeg 768w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.26.11-PM.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.33.37-PM-1-1024x576.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.33.37-PM-1-1024x576.jpeg\" alt=\"\" data-id=\"10649\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10649\" class=\"wp-image-10649\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.33.37-PM-1-1024x576.jpeg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.33.37-PM-1-300x169.jpeg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.33.37-PM-1-768x432.jpeg 768w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.33.37-PM-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.35.34-PM-2-1024x576.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.35.34-PM-2-1024x576.jpeg\" alt=\"\" data-id=\"10650\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10650\" class=\"wp-image-10650\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.35.34-PM-2-1024x576.jpeg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.35.34-PM-2-300x169.jpeg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.35.34-PM-2-768x432.jpeg 768w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.35.34-PM-2.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.57.24-PM-1024x576.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.57.24-PM-1024x576.jpeg\" alt=\"\" data-id=\"10651\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10651\" class=\"wp-image-10651\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.57.24-PM-1024x576.jpeg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.57.24-PM-300x169.jpeg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.57.24-PM-768x432.jpeg 768w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-1.57.24-PM.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.03.51-PM-1-1024x576.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.03.51-PM-1-1024x576.jpeg\" alt=\"\" data-id=\"10652\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10652\" class=\"wp-image-10652\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.03.51-PM-1-1024x576.jpeg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.03.51-PM-1-300x169.jpeg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.03.51-PM-1-768x432.jpeg 768w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.03.51-PM-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.19.13-PM-1-1024x576.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.19.13-PM-1-1024x576.jpeg\" alt=\"\" data-id=\"10653\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10653\" class=\"wp-image-10653\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.19.13-PM-1-1024x576.jpeg 1024w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.19.13-PM-1-300x169.jpeg 300w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.19.13-PM-1-768x432.jpeg 768w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.19.13-PM-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.20.59-PM-576x1024.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.20.59-PM-576x1024.jpeg\" alt=\"\" data-id=\"10654\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10654\" class=\"wp-image-10654\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.20.59-PM-576x1024.jpeg 576w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.20.59-PM-169x300.jpeg 169w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.20.59-PM.jpeg 720w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.21.11-PM-1-576x1024.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.21.11-PM-1-576x1024.jpeg\" alt=\"\" data-id=\"10655\" data-link=\"https:\/\/www.une.edu.pe\/uneweb\/?attachment_id=10655\" class=\"wp-image-10655\" srcset=\"https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.21.11-PM-1-576x1024.jpeg 576w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.21.11-PM-1-169x300.jpeg 169w, https:\/\/www.une.edu.pe\/uneweb\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2022-03-09-at-2.21.11-PM-1.jpeg 720w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/a><\/figure><\/li><\/ul>\n ","protected":false},"excerpt":{"rendered":"<p>Nota de Prensa N\u00b0 019-2022-OII-UNE Con el prop\u00f3sito de redescubrir, repoblar y concientizar sobre la importancia medicinal, ambiental y forestal del \u00e1rbol de la quina, esta tarde se realiz\u00f3 la siembra de esta planta en la sede central de la Universidad Nacional de Educaci\u00f3n Enrique Guzm\u00e1n y Valle, en el marco de las celebraciones por [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts\/10639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/comments?post=10639"}],"version-history":[{"count":1,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts\/10639\/revisions"}],"predecessor-version":[{"id":10656,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/posts\/10639\/revisions\/10656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/media\/10640"}],"wp:attachment":[{"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/media?parent=10639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/categories?post=10639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.une.edu.pe\/uneweb\/wp-json\/wp\/v2\/tags?post=10639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}